{"id":8197,"date":"2025-12-09T15:23:25","date_gmt":"2025-12-09T15:23:25","guid":{"rendered":"https:\/\/pinedesign.nl\/product\/esstisch-royal\/"},"modified":"2025-12-09T15:23:25","modified_gmt":"2025-12-09T15:23:25","slug":"esstisch-royal","status":"publish","type":"product","link":"https:\/\/pinedesign.nl\/de\/product\/esstisch-royal\/","title":{"rendered":"Esstisch Royal"},"content":{"rendered":"<p data-start=\"153\" data-end=\"470\">Entdecke den <strong data-start=\"163\" data-end=\"172\">Royal<\/strong>: ein prachtvoller, massiver Esstisch, der sofort das Herz deines Interieurs erobert. Mit seiner <strong data-start=\"268\" data-end=\"290\">robusten, dicken Platte<\/strong> und den <strong data-start=\"294\" data-end=\"314\">stilvollen Beinen<\/strong> strahlt dieser Tisch pure Klasse und W\u00e4rme aus. Ob modern, l\u00e4ndlich oder zeitlos \u2013 der Royal passt sich m\u00fchelos deinem Wohnstil an.  <\/p>\n<p data-start=\"472\" data-end=\"736\">Dieser Esstisch ist <strong data-start=\"489\" data-end=\"510\">vollst\u00e4ndige Ma\u00dfarbeit<\/strong>.<br data-start=\"511\" data-end=\"514\">W\u00fcnschst du dir ein anderes Ma\u00df? Kein Problem.<br data-start=\"552\" data-end=\"555\">Lieber ein anderes Tischbein? Auch das erledigen wir gerne.<br data-start=\"615\" data-end=\"618\">Der Royal ist in <strong data-start=\"643\" data-end=\"676\">verschiedenen Ma\u00dfen und Farben<\/strong> erh\u00e4ltlich, damit er perfekt zu deinen W\u00fcnschen und deinem Raum passt.  <\/p>\n<p data-start=\"738\" data-end=\"926\">Komm in unserem Gesch\u00e4ft vorbei und erlebe die Qualit\u00e4t, das Handwerk und die Ausstrahlung des Royal selbst.<br data-start=\"839\" data-end=\"842\">Wir beraten dich gerne und helfen dir, einen Tisch zu kreieren, der wirklich zu dir passt.<\/p>\n<p data-start=\"928\" data-end=\"1012\"><strong data-start=\"928\" data-end=\"1010\">Der Royal \u2013 nicht nur ein Esstisch, sondern der neue Mittelpunkt deines Zuhauses.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p data-start=\"153\" data-end=\"470\">Entdecke den <strong data-start=\"163\" data-end=\"172\">Royal<\/strong>: ein prachtvoller, massiver Esstisch, der sofort das Herz deines Interieurs erobert. Mit seiner <strong data-start=\"268\" data-end=\"290\">robusten, dicken Platte<\/strong> und den <strong data-start=\"294\" data-end=\"314\">stilvollen Beinen<\/strong> strahlt dieser Tisch pure Klasse und W\u00e4rme aus. Ob modern, l\u00e4ndlich oder zeitlos \u2013 der Royal passt sich m\u00fchelos deinem Wohnstil an.  <\/p>\n<p data-start=\"472\" data-end=\"736\">Dieser Esstisch ist <strong data-start=\"489\" data-end=\"510\">vollst\u00e4ndige Ma\u00dfarbeit<\/strong>.<br data-start=\"511\" data-end=\"514\">W\u00fcnschst du dir ein anderes Ma\u00df? Kein Problem.<br data-start=\"552\" data-end=\"555\">Lieber ein anderes Tischbein? Auch das erledigen wir gerne.<br data-start=\"615\" data-end=\"618\">Der Royal ist in <strong data-start=\"643\" data-end=\"676\">verschiedenen Ma\u00dfen und Farben<\/strong> erh\u00e4ltlich, damit er perfekt zu deinen W\u00fcnschen und deinem Raum passt.  <\/p>\n<p data-start=\"738\" data-end=\"926\">Komm in unserem Gesch\u00e4ft vorbei und erlebe die Qualit\u00e4t, das Handwerk und die Ausstrahlung des Royal selbst.<br data-start=\"839\" data-end=\"842\">Wir beraten dich gerne und helfen dir, einen Tisch zu kreieren, der wirklich zu dir passt.<\/p>\n<p data-start=\"928\" data-end=\"1012\"><strong data-start=\"928\" data-end=\"1010\">Der Royal \u2013 nicht nur ein Esstisch, sondern der neue Mittelpunkt deines Zuhauses.<\/strong><\/p>\n","protected":false},"featured_media":6928,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[122,121],"product_tag":[],"class_list":["post-8197","product","type-product","status-publish","has-post-thumbnail","product_cat-esstische","product_cat-tische","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/product\/8197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/media\/6928"}],"wp:attachment":[{"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/media?parent=8197"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/product_brand?post=8197"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/product_cat?post=8197"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/product_tag?post=8197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}