{"id":8146,"date":"2025-08-28T13:16:32","date_gmt":"2025-08-28T13:16:32","guid":{"rendered":"https:\/\/pinedesign.nl\/product\/barhocker-oliver\/"},"modified":"2025-08-28T13:16:32","modified_gmt":"2025-08-28T13:16:32","slug":"barhocker-oliver","status":"publish","type":"product","link":"https:\/\/pinedesign.nl\/de\/product\/barhocker-oliver\/","title":{"rendered":"Barhocker Oliver"},"content":{"rendered":"<p data-start=\"79\" data-end=\"426\"><strong data-start=\"79\" data-end=\"138\">Barhocker Oliver \u2013 stilvoll, komfortabel und ganz dein Stil<\/strong><br data-start=\"138\" data-end=\"141\">Vervollst\u00e4ndige deine K\u00fcche oder Bar mit dem Oliver <strong data-start=\"179\" data-end=\"194\">Barhocker<\/strong>, der f\u00fcr einen einheitlichen und stilvollen Look in deiner Einrichtung sorgt. Mit der <strong data-start=\"274\" data-end=\"317\">innovativen Dreh- und R\u00fcckholfunktion<\/strong> kehrt der Hocker nach Gebrauch immer ordentlich in seine urspr\u00fcngliche Position zur\u00fcck \u2013 praktisch und bequem. <\/p>\n<p data-start=\"428\" data-end=\"687\">Der Barhocker Oliver ist in <strong data-start=\"462\" data-end=\"492\">zwei verschiedenen H\u00f6hen<\/strong> erh\u00e4ltlich, sodass er perfekt zu deiner K\u00fcche oder Bar passt. Zudem kannst du aus <strong data-start=\"567\" data-end=\"594\">48 hochwertigen Stoffen<\/strong> w\u00e4hlen, damit der Barhocker ideal auf deinen pers\u00f6nlichen Stil und deine restliche Einrichtung abgestimmt ist. <\/p>\n<p data-start=\"689\" data-end=\"797\">\ud83d\udc49 Komm in unserem Gesch\u00e4ft vorbei und erlebe selbst, wie der Barhocker Oliver Design, Komfort und Benutzerfreundlichkeit vereint.<\/p>\n","protected":false},"excerpt":{"rendered":"<p data-start=\"79\" data-end=\"426\"><strong data-start=\"79\" data-end=\"138\">Barhocker Oliver \u2013 stilvoll, komfortabel und ganz dein Stil<\/strong><br data-start=\"138\" data-end=\"141\">Vervollst\u00e4ndige deine K\u00fcche oder Bar mit dem Oliver <strong data-start=\"179\" data-end=\"194\">Barhocker<\/strong>, der f\u00fcr einen einheitlichen und stilvollen Look in deiner Einrichtung sorgt. Mit der <strong data-start=\"274\" data-end=\"317\">innovativen Dreh- und R\u00fcckholfunktion<\/strong> kehrt der Hocker nach Gebrauch immer ordentlich in seine urspr\u00fcngliche Position zur\u00fcck \u2013 praktisch und bequem. <\/p>\n<p data-start=\"428\" data-end=\"687\">Der Barhocker Oliver ist in <strong data-start=\"462\" data-end=\"492\">zwei verschiedenen H\u00f6hen<\/strong> erh\u00e4ltlich, sodass er perfekt zu deiner K\u00fcche oder Bar passt. Zudem kannst du aus <strong data-start=\"567\" data-end=\"594\">48 hochwertigen Stoffen<\/strong> w\u00e4hlen, damit der Barhocker ideal auf deinen pers\u00f6nlichen Stil und deine restliche Einrichtung abgestimmt ist. <\/p>\n<p data-start=\"689\" data-end=\"797\">\ud83d\udc49 Komm in unserem Gesch\u00e4ft vorbei und erlebe selbst, wie der Barhocker Oliver Design, Komfort und Benutzerfreundlichkeit vereint.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[141,155,136,124],"product_tag":[],"class_list":["post-8146","product","type-product","status-publish","product_cat-barhocker","product_cat-gusj","product_cat-marken","product_cat-sitzmobel","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/product\/8146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/media?parent=8146"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/product_brand?post=8146"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/product_cat?post=8146"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pinedesign.nl\/de\/wp-json\/wp\/v2\/product_tag?post=8146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}